{"id":17731,"date":"2025-01-29T21:03:52","date_gmt":"2025-01-29T21:03:52","guid":{"rendered":"https:\/\/lacasadelguatin.co\/?p=17731"},"modified":"2025-01-29T21:06:50","modified_gmt":"2025-01-29T21:06:50","slug":"cronograma-actualizado-de-nuestras-actividades","status":"publish","type":"post","link":"https:\/\/lacasadelguatin.co\/index.php\/2025\/01\/29\/cronograma-actualizado-de-nuestras-actividades\/","title":{"rendered":"Cronograma actualizado de nuestras actividades"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/lacasadelguatin.co\/wp-content\/uploads\/2025\/01\/Imagen-de-WhatsApp-2025-01-29-a-las-11.28.00_d223d084-1024x576.jpg\" alt=\"\" class=\"wp-image-17732\" srcset=\"https:\/\/lacasadelguatin.co\/wp-content\/uploads\/2025\/01\/Imagen-de-WhatsApp-2025-01-29-a-las-11.28.00_d223d084-1024x576.jpg 1024w, https:\/\/lacasadelguatin.co\/wp-content\/uploads\/2025\/01\/Imagen-de-WhatsApp-2025-01-29-a-las-11.28.00_d223d084-300x169.jpg 300w, https:\/\/lacasadelguatin.co\/wp-content\/uploads\/2025\/01\/Imagen-de-WhatsApp-2025-01-29-a-las-11.28.00_d223d084-768x432.jpg 768w, https:\/\/lacasadelguatin.co\/wp-content\/uploads\/2025\/01\/Imagen-de-WhatsApp-2025-01-29-a-las-11.28.00_d223d084.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cronograma actualizado de las actividades en el Centro Cultural de La Buitrera, CCBU La Guatina. Invitamos a la comunidad buitrere\u00f1a a compartir esta informaci\u00f3n en sus redes para que m\u00e1s vecinos conozcan de la existencia de este lugar y puedan aprovechar la oferta cultural y art\u00edstica que ac\u00e1 ofrecemos. <br>Si estas interesado en alg\u00fan taller, puedes obtener mayor informaci\u00f3n e inscribirte directamente con el tallerista\/profesor -en el cuadro est\u00e1 la informaci\u00f3n completa de contacto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cronograma actualizado de las actividades en el Centro Cultural de La Buitrera, CCBU La Guatina. Invitamos a la comunidad buitrere\u00f1a a compartir esta informaci\u00f3n en sus redes para que m\u00e1s vecinos conozcan de la existencia de este lugar y puedan aprovechar la oferta cultural y art\u00edstica que ac\u00e1 ofrecemos. Si estas interesado en alg\u00fan taller, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17732,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_joinchat":[],"footnotes":""},"categories":[412,1],"tags":[],"class_list":["post-17731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-250129-cronograma-actualizado-de-nuestras-actividades","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/17731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/comments?post=17731"}],"version-history":[{"count":0,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/17731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media\/17732"}],"wp:attachment":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media?parent=17731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/categories?post=17731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/tags?post=17731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}