{"id":16922,"date":"2024-11-13T18:46:53","date_gmt":"2024-11-13T18:46:53","guid":{"rendered":"https:\/\/lacasadelguatin.co\/?p=16922"},"modified":"2024-11-13T18:46:54","modified_gmt":"2024-11-13T18:46:54","slug":"taller-de-helados-caseros-para-nnaj-ninas-ninos-y-jovenes-este-sabado-16-de-noviembre","status":"publish","type":"post","link":"https:\/\/lacasadelguatin.co\/index.php\/2024\/11\/13\/taller-de-helados-caseros-para-nnaj-ninas-ninos-y-jovenes-este-sabado-16-de-noviembre\/","title":{"rendered":"Taller de helados caseros para NNAJ -ni\u00f1as, ni\u00f1os y j\u00f3venes- este s\u00e1bado 16 de noviembre."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Guatina te invita a este divertido taller; \u00fanete a nosotros para una divertida y deliciosa actividad donde aprenderemos a hacer helados caseros. Este taller es ideal para todas las edades y no necesitas experiencia previa.<br>Costo: $6.000<br>Cupo M\u00e1ximo: 12 NI\u00d1OS<br>\u00a1Te esperamos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fecha: S\u00e1bado, 16 de noviembre de 2024<br>Horario: 4:00 pm a 6:00 pm<br>Reserva tu cupo y disfruta de una tarde de sabor y creatividad.<br>Informes e inscripciones con Zulamita Jaramillo\u00a0321\u00a07522860<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Guatina te invita a este divertido taller; \u00fanete a nosotros para una divertida y deliciosa actividad donde aprenderemos a hacer helados caseros. Este taller es ideal para todas las edades y no necesitas experiencia previa.Costo: $6.000Cupo M\u00e1ximo: 12 NI\u00d1OS\u00a1Te esperamos! Fecha: S\u00e1bado, 16 de noviembre de 2024Horario: 4:00 pm a 6:00 pmReserva tu cupo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"categories":[377],"tags":[],"class_list":["post-16922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-241112-taller-de-helados-nnaj"],"_links":{"self":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/16922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/comments?post=16922"}],"version-history":[{"count":0,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/16922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media\/16923"}],"wp:attachment":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media?parent=16922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/categories?post=16922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/tags?post=16922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}