{"id":15677,"date":"2024-08-28T14:32:12","date_gmt":"2024-08-28T14:32:12","guid":{"rendered":"https:\/\/lacasadelguatin.co\/?p=15677"},"modified":"2024-08-28T14:32:13","modified_gmt":"2024-08-28T14:32:13","slug":"nueva-actividad-en-la-guatina-taller-de-cocina-vegetariana-con-abhay-charan-g","status":"publish","type":"post","link":"https:\/\/lacasadelguatin.co\/index.php\/2024\/08\/28\/nueva-actividad-en-la-guatina-taller-de-cocina-vegetariana-con-abhay-charan-g\/","title":{"rendered":"Nueva actividad en La Guatina: Taller de cocina vegetariana con Abhay Charan G."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a1Descubre el arte de la cocina vegetariana!, en este taller especializado en gastronom\u00eda hind\u00fa.<br>Aprende las t\u00e9cnicas esenciales para preparar una variedad de platos vegetarianos deliciosos y saludables, utilizando especias y combinaciones \u00fanicas de vegetales, cereales y l\u00e1cteos.<br>En este taller te guiar\u00e1n a trav\u00e9s de 7 recetas cuidadosamente elaboradas, dise\u00f1adas para ofrecerte un almuerzo vegetariano exquisito y completo. <br>Disfruta de una experiencia culinaria en un entorno natural y relajante, rodeado del canto de los p\u00e1jaros.<br>Valor por persona: $50.000 (incluye ingredientes). Pago anticipado<br>Fecha: Domingo 01 de Septiembre Hora: 9:00 am a 3:00 pm<br>Lugar: La Guatina, km 3, Callej\u00f3n frente al Centro de Salud, casa #8.<br>Cupo m\u00ednimo 6 y m\u00e1ximo 7 personas.<br><strong>NOTA: <\/strong><br>Inscripciones hasta el viernes 30 de agosto a las 6:00 pm.<br>Mayores detalles con Abhay Charan Guill\u00e9n 318 825 9499<br>!Te\u00a0esperamos\u00a1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Descubre el arte de la cocina vegetariana!, en este taller especializado en gastronom\u00eda hind\u00fa.Aprende las t\u00e9cnicas esenciales para preparar una variedad de platos vegetarianos deliciosos y saludables, utilizando especias y combinaciones \u00fanicas de vegetales, cereales y l\u00e1cteos.En este taller te guiar\u00e1n a trav\u00e9s de 7 recetas cuidadosamente elaboradas, dise\u00f1adas para ofrecerte un almuerzo vegetariano exquisito [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15678,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_joinchat":[],"footnotes":""},"categories":[334],"tags":[],"class_list":["post-15677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-240828-nueva-actividad-en-la-guatina"],"_links":{"self":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/15677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/comments?post=15677"}],"version-history":[{"count":0,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/15677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media\/15678"}],"wp:attachment":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media?parent=15677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/categories?post=15677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/tags?post=15677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}