{"id":15644,"date":"2024-08-24T01:55:38","date_gmt":"2024-08-24T01:55:38","guid":{"rendered":"https:\/\/lacasadelguatin.co\/?p=15644"},"modified":"2024-08-24T01:55:39","modified_gmt":"2024-08-24T01:55:39","slug":"vamos-a-jugar","status":"publish","type":"post","link":"https:\/\/lacasadelguatin.co\/index.php\/2024\/08\/24\/vamos-a-jugar\/","title":{"rendered":"Vamos a jugar"},"content":{"rendered":"\n<figure class=\"wp-block-video\"><video height=\"478\" style=\"aspect-ratio: 848 \/ 478;\" width=\"848\" controls src=\"https:\/\/lacasadelguatin.co\/wp-content\/uploads\/2024\/08\/Video-de-WhatsApp-2024-08-23-a-las-16.53.36_e59905be.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Este s\u00e1bado 24 de agosto, ven y disfruta de un d\u00eda lleno de diversi\u00f3n en La Guatina! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estaremos ofreciendo un espacio especial para juegos de mesa, donde personas de todas las edades podr\u00e1n compartir y divertirse. Desde cl\u00e1sicos hasta novedades, tenemos algo para todos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aprovecha esta oportunidad de pasar un rato agradable\u00a0en\u00a0comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Este s\u00e1bado 24 de agosto, ven y disfruta de un d\u00eda lleno de diversi\u00f3n en La Guatina! Estaremos ofreciendo un espacio especial para juegos de mesa, donde personas de todas las edades podr\u00e1n compartir y divertirse. Desde cl\u00e1sicos hasta novedades, tenemos algo para todos. Aprovecha esta oportunidad de pasar un rato agradable\u00a0en\u00a0comunidad.<\/p>\n","protected":false},"author":1,"featured_media":15646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"categories":[332],"tags":[],"class_list":["post-15644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-240823-vamos-a-jugar"],"_links":{"self":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/15644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/comments?post=15644"}],"version-history":[{"count":0,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/15644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media\/15646"}],"wp:attachment":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media?parent=15644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/categories?post=15644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/tags?post=15644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}