{"id":15130,"date":"2024-07-29T17:21:01","date_gmt":"2024-07-29T17:21:01","guid":{"rendered":"https:\/\/lacasadelguatin.co\/?p=15130"},"modified":"2024-07-29T17:21:02","modified_gmt":"2024-07-29T17:21:02","slug":"termometro-de-la-vida-temporada-de-amor-propio","status":"publish","type":"post","link":"https:\/\/lacasadelguatin.co\/index.php\/2024\/07\/29\/termometro-de-la-vida-temporada-de-amor-propio\/","title":{"rendered":"Term\u00f3metro de la vida. Temporada de amor propio."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Guatina Centro Cultural presenta:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Charla\/Taller Temporada De Amor Propio<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coach: Jackelin Patichoy<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\uddd3 *Primer martes de cada mes\u0003<br>\u23f0 7:00 pm a 8:00 pm<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inversi\u00f3n:<br>$10.000 Clase<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcdeInscripciones \/ Info: 316\u00a0692\u00a01889<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Guatina Centro Cultural presenta: Charla\/Taller Temporada De Amor Propio Coach: Jackelin Patichoy \ud83d\uddd3 *Primer martes de cada mes\u0003\u23f0 7:00 pm a 8:00 pm Inversi\u00f3n:$10.000 Clase \ud83d\udcdeInscripciones \/ Info: 316\u00a0692\u00a01889<\/p>\n","protected":false},"author":1,"featured_media":15131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[],"footnotes":""},"categories":[318],"tags":[],"class_list":["post-15130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-103-termometro-de-la-vida-temporada-de-amor-propio"],"_links":{"self":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/15130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/comments?post=15130"}],"version-history":[{"count":0,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/posts\/15130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media\/15131"}],"wp:attachment":[{"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/media?parent=15130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/categories?post=15130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacasadelguatin.co\/index.php\/wp-json\/wp\/v2\/tags?post=15130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}